{"id":59573,"date":"2022-12-02T17:49:47","date_gmt":"2022-12-02T16:49:47","guid":{"rendered":"https:\/\/pirellihangarbicocca.org\/?post_type=bubble&#038;p=59573"},"modified":"2022-12-02T19:01:59","modified_gmt":"2022-12-02T18:01:59","slug":"catalogue-extract-dineo-seshee-bopape-kwanele-sosibo","status":"publish","type":"bubble","link":"https:\/\/pirellihangarbicocca.org\/en\/bubble\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\/","title":{"rendered":"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape"},"template":"","tags":[1410,954,922,1289],"bubble_type":[813],"class_list":["post-59573","bubble","type-bubble","status-publish","hentry","tag-brorn-in-the-first-light-of-the-morning-moswaramarapo","tag-bubbles-en","tag-catalogue","tag-dineo-seshee-bopape-en","bubble_type-read"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape - Pirelli HangarBicocca<\/title>\n<meta name=\"description\" content=\"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape - Discover on Pirelli HangarBicocca!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pirellihangarbicocca.org\/en\/bubble\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape - Pirelli HangarBicocca\" \/>\n<meta property=\"og:description\" content=\"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape - Discover on Pirelli HangarBicocca!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pirellihangarbicocca.org\/en\/bubble\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\/\" \/>\n<meta property=\"og:site_name\" content=\"Pirelli HangarBicocca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PirelliHangarBicocca\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-02T18:01:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web-assets-hangarbicocca.pirelli.com\/wp-content\/uploads\/2024\/12\/Pirelli-HangarBicocca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@HangarBicocca\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/bubble\\\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\\\/\",\"url\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/bubble\\\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\\\/\",\"name\":\"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape - Pirelli HangarBicocca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/#website\"},\"datePublished\":\"2022-12-02T16:49:47+00:00\",\"dateModified\":\"2022-12-02T18:01:59+00:00\",\"description\":\"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape - Discover on Pirelli HangarBicocca!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/bubble\\\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/bubble\\\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/bubble\\\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bubbles\",\"item\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/bubble\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Read\",\"item\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/bubble-type\\\/read\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/\",\"name\":\"Pirelli HangarBicocca\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/#organization\",\"name\":\"Pirelli HangarBicocca\",\"url\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/web-assets-hangarbicocca.pirelli.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/pirelli-hangarbicocca.png\",\"contentUrl\":\"https:\\\/\\\/web-assets-hangarbicocca.pirelli.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/pirelli-hangarbicocca.png\",\"width\":496,\"height\":48,\"caption\":\"Pirelli HangarBicocca\"},\"image\":{\"@id\":\"https:\\\/\\\/pirellihangarbicocca.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PirelliHangarBicocca\\\/\",\"https:\\\/\\\/x.com\\\/HangarBicocca\",\"https:\\\/\\\/www.instagram.com\\\/pirelli_hangarbicocca\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/HangarBicocca\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape - Pirelli HangarBicocca","description":"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape - Discover on Pirelli HangarBicocca!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pirellihangarbicocca.org\/en\/bubble\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\/","og_locale":"en_US","og_type":"article","og_title":"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape - Pirelli HangarBicocca","og_description":"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape - Discover on Pirelli HangarBicocca!","og_url":"https:\/\/pirellihangarbicocca.org\/en\/bubble\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\/","og_site_name":"Pirelli HangarBicocca","article_publisher":"https:\/\/www.facebook.com\/PirelliHangarBicocca\/","article_modified_time":"2022-12-02T18:01:59+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/web-assets-hangarbicocca.pirelli.com\/wp-content\/uploads\/2024\/12\/Pirelli-HangarBicocca.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@HangarBicocca","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pirellihangarbicocca.org\/en\/bubble\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\/","url":"https:\/\/pirellihangarbicocca.org\/en\/bubble\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\/","name":"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape - Pirelli HangarBicocca","isPartOf":{"@id":"https:\/\/pirellihangarbicocca.org\/en\/#website"},"datePublished":"2022-12-02T16:49:47+00:00","dateModified":"2022-12-02T18:01:59+00:00","description":"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape - Discover on Pirelli HangarBicocca!","breadcrumb":{"@id":"https:\/\/pirellihangarbicocca.org\/en\/bubble\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pirellihangarbicocca.org\/en\/bubble\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pirellihangarbicocca.org\/en\/bubble\/catalogue-extract-dineo-seshee-bopape-kwanele-sosibo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pirellihangarbicocca.org\/en\/"},{"@type":"ListItem","position":2,"name":"Bubbles","item":"https:\/\/pirellihangarbicocca.org\/en\/bubble\/"},{"@type":"ListItem","position":3,"name":"Read","item":"https:\/\/pirellihangarbicocca.org\/en\/bubble-type\/read\/"},{"@type":"ListItem","position":4,"name":"Catalogue extract, text by Kwanele Sosibo | Dineo Seshee Bopape"}]},{"@type":"WebSite","@id":"https:\/\/pirellihangarbicocca.org\/en\/#website","url":"https:\/\/pirellihangarbicocca.org\/en\/","name":"Pirelli HangarBicocca","description":"","publisher":{"@id":"https:\/\/pirellihangarbicocca.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pirellihangarbicocca.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pirellihangarbicocca.org\/en\/#organization","name":"Pirelli HangarBicocca","url":"https:\/\/pirellihangarbicocca.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pirellihangarbicocca.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/web-assets-hangarbicocca.pirelli.com\/wp-content\/uploads\/2019\/06\/pirelli-hangarbicocca.png","contentUrl":"https:\/\/web-assets-hangarbicocca.pirelli.com\/wp-content\/uploads\/2019\/06\/pirelli-hangarbicocca.png","width":496,"height":48,"caption":"Pirelli HangarBicocca"},"image":{"@id":"https:\/\/pirellihangarbicocca.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PirelliHangarBicocca\/","https:\/\/x.com\/HangarBicocca","https:\/\/www.instagram.com\/pirelli_hangarbicocca\/","http:\/\/www.youtube.com\/user\/HangarBicocca"]}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/pirellihangarbicocca.org\/en\/wp-json\/wp\/v2\/bubble\/59573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pirellihangarbicocca.org\/en\/wp-json\/wp\/v2\/bubble"}],"about":[{"href":"https:\/\/pirellihangarbicocca.org\/en\/wp-json\/wp\/v2\/types\/bubble"}],"wp:attachment":[{"href":"https:\/\/pirellihangarbicocca.org\/en\/wp-json\/wp\/v2\/media?parent=59573"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pirellihangarbicocca.org\/en\/wp-json\/wp\/v2\/tags?post=59573"},{"taxonomy":"bubble_type","embeddable":true,"href":"https:\/\/pirellihangarbicocca.org\/en\/wp-json\/wp\/v2\/bubble_type?post=59573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}